{"id":3851,"date":"2021-12-07T02:11:19","date_gmt":"2021-12-07T02:11:19","guid":{"rendered":"https:\/\/blogs.ugto.mx\/contador\/?p=3851"},"modified":"2021-12-09T21:39:55","modified_gmt":"2021-12-09T21:39:55","slug":"clase-digital-4-clasificadores-presupuestarios","status":"publish","type":"post","link":"https:\/\/blogs.ugto.mx\/contador\/clase-digital-4-clasificadores-presupuestarios\/","title":{"rendered":"Clase digital 4. Clasificadores presupuestarios"},"content":{"rendered":"\n\n\n<div class=\"wp-block-cover has-background-dim-40 has-black-background-color has-background-dim\" style=\"min-height:284px;aspect-ratio:unset;\"><img decoding=\"async\" class=\"wp-block-cover__image-background wp-image-3852\" alt=\"\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/blogs.ugto.mx\/contador\/wp-content\/uploads\/sites\/68\/2021\/12\/sbxdmooy9zm.jpg\" style=\"object-position:55% 77%\" data-object-fit=\"cover\" data-object-position=\"55% 77%\" \/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1069\" class=\"wp-block-cover__image-background wp-image-3852\" alt=\"\" src=\"https:\/\/blogs.ugto.mx\/contador\/wp-content\/uploads\/sites\/68\/2021\/12\/sbxdmooy9zm.jpg\" style=\"object-position:55% 77%\" data-object-fit=\"cover\" data-object-position=\"55% 77%\" srcset=\"https:\/\/blogs.ugto.mx\/contador\/wp-content\/uploads\/sites\/68\/2021\/12\/sbxdmooy9zm.jpg 1600w, https:\/\/blogs.ugto.mx\/contador\/wp-content\/uploads\/sites\/68\/2021\/12\/sbxdmooy9zm-300x200.jpg 300w, https:\/\/blogs.ugto.mx\/contador\/wp-content\/uploads\/sites\/68\/2021\/12\/sbxdmooy9zm-1024x684.jpg 1024w, https:\/\/blogs.ugto.mx\/contador\/wp-content\/uploads\/sites\/68\/2021\/12\/sbxdmooy9zm-768x513.jpg 768w, https:\/\/blogs.ugto.mx\/contador\/wp-content\/uploads\/sites\/68\/2021\/12\/sbxdmooy9zm-1536x1026.jpg 1536w, https:\/\/blogs.ugto.mx\/contador\/wp-content\/uploads\/sites\/68\/2021\/12\/sbxdmooy9zm-272x182.jpg 272w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/noscript><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\">Clasificadores presupuestarios<\/p>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">1. Fundamentaci\u00f3n del tema<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Es de suma importancia que dentro de la formaci\u00f3n del Contador P\u00fablico se imparta el conocimiento de la t\u00e9cnica contable correspondiente al sector gubernamental. Especialmente, este tema tiene gran relevancia, toda vez que la Ley General de Contabilidad Gubernamental, se\u00f1ala en su art\u00edculo 41 que los entes p\u00fablicos deben disponer de clasificadores presupuestarios, as\u00ed como otras herramientas que permitan relacionar autom\u00e1ticamente entre s\u00ed, todas las operaciones presupuestarias y contables registradas. <\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">(LGCG, 2018)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es decir, los clasificadores presupuestarios ayudar\u00e1n a establecer una relaci\u00f3n y armonizaci\u00f3n contable entre los entes p\u00fablicos.&nbsp; Por lo anterior, no es posible que el contador p\u00fablico omita tener nociones b\u00e1sicas de los clasificadores presupuestarios empleados en las instituciones gubernamentales, y aun cuando no desee desempe\u00f1arse en dicho sector deber\u00e1 poseer el conocimiento general sobre el tema.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">2. Objetivo did\u00e1ctico<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Comprender qu\u00e9 son los clasificadores presupuestarios, y cual es la funci\u00f3n de cada uno de ellos, para asimilar c\u00f3mo funciona de manera integral el Sistema de Contabilidad Gubernamental.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">3. Contenido did\u00e1ctico<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Introducci\u00f3n<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Hola! Se bienvenido una vez m\u00e1s a un recurso digital de la Universidad de Guanajuato en el cual continuaremos con el an\u00e1lisis de la Unidad de Aprendizaje de Contabilidad Gubernamental. En esta ocasi\u00f3n, estudiaremos el tema de clasificadores presupuestarios, los cuales, resultan muy relevantes ya que ayudan a registrar las operaciones contables y presupuestarias de los entes p\u00fablicos. Gracias a estos clasificadores se pueden presentar datos armonizados y coherentes, que ayuden al proceso de transparencia y rendici\u00f3n de cuentas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, gracias a la clasificaci\u00f3n que se hace tanto para ingresos como para egresos es posible analizar el comportamiento de los entes p\u00fablicos, y evaluar la aplicaci\u00f3n de los recursos que se les destinan. As\u00ed mismo, a partir de los clasificadores se puede asignar con mayor eficiencia los recursos e incluso crear o modificar pol\u00edticas p\u00fablicas. <\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">(Davina Jacobs, 2009)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es por ello, que resulta indispensable que comprendas, al menos de manera general, cada uno de los siete clasificadores presupuestarios que se enlistan a continuaci\u00f3n:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Clasificador por Rubro de Ingresos<\/li><li>Clasificaci\u00f3n Administrativa<\/li><li>Clasificaci\u00f3n Funcional del Gasto<\/li><li>Clasificaci\u00f3n Program\u00e1tica<\/li><li>Clasificador Econ\u00f3mico (Por Tipo de Gasto)<\/li><li>Clasificador por Fuentes de Financiamiento<\/li><li>Clasificador por Objeto del Gasto Armonizado<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Esperamos que este recurso sea de gran utilidad para tu desarrollo acad\u00e9mico. Sin mayor pre\u00e1mbulo, \u00a1Comencemos!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Desarrollo del tema<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Como la LGC se\u00f1ala, en el a\u00f1o 2009, el Consejo Nacional de Armonizaci\u00f3n Contables (CONAC) emiti\u00f3 los clasificadores presupuestarios armonizados, qu\u00e9 se deber\u00edan emplear para el registro de las transacciones econ\u00f3micas de los entes p\u00fablicos. A continuaci\u00f3n, se explicar\u00e1 de manera sintetizada cada uno de ellos, si deseas obtener informaci\u00f3n adicional, puedes consultar la p\u00e1gina del CONAC, en su apartado de normatividad vigente, y en \u201cPrincipales Elementos del Sistema de Contabilidad Gubernamental\u201d. <\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">(LGCG, 2018)<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Clasificador por rubros de ingresos<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Comenzaremos con el Clasificador por Rubros De Ingresos (CRI). El principal objetivo de este clasificador es identificar los ingresos que perciben los entes p\u00fablicos de acuerdo con la funci\u00f3n y actividad que desarrollan. Gracias a este sistema se puede analizar el comportamiento de los ingresos y facilitar la toma adecuada de decisiones, Asimismo se puede analizar de d\u00f3nde provienen los recursos y en qu\u00e9 proporci\u00f3n. En otras palabras, el CRI agrupan los ingresos p\u00fablicos seg\u00fan su naturaleza u origen. De este modo, se identifican las fuentes normales de los recursos tales como impuestos, aprovechamientos, derechos y productos, y transferencias. Tambi\u00e9n se identifican los que provienen del patrimonio p\u00fablico, por ejemplo, la venta de activos, de t\u00edtulos, de acciones, entre otros. Finalmente tambi\u00e9n se clasifican aquellos ingresos que provienen de una disminuci\u00f3n de activos, o bien son resultado de alg\u00fan financiamiento. <\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">(CONAC, 2009)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al igual que en un cat\u00e1logo de cuentas del sector privado, existe una numeraci\u00f3n que da orden y sentido a las cuentas que se emplean. Esta serie de n\u00fameros, es denominada codificaci\u00f3n y se compone primeramente por dos d\u00edgitos. El primer nivel es llamado rubro, el cual presenta y ordena los ingresos p\u00fablicos en los principales grupos seg\u00fan su naturaleza y origen. Despu\u00e9s, se muestra el tipo de ingreso que corresponde a ese rubro. Del mismo modo, cada Gobierno puede emplear un tercer y cuarto nivel de acuerdo a sus necesidades, los cuales se denominan clase y concepto, respectivamente. <\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">(CONAC, 2009)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los rubros que este clasificador considera son: impuestos, cuotas y aportaciones de Seguridad Social, contribuciones de mejoras, derechos, productos, aprovechamientos; ingresos por venta de bienes, prestaci\u00f3n de servicios y otros ingresos; Participaciones, Aportaciones, Convenios, Incentivos Derivados de la Colaboraci\u00f3n Fiscal y Fondos Distintos de Aportaciones; Transferencias, Asignaciones, Subsidios y Subvenciones, y Pensiones y Jubilaciones,y finalmente, los Ingresos Derivados de Financiamientos. <\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">(CONAC, 2009)<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Clasificaci\u00f3n administrativa<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">El objetivo de este clasificador es diferenciar los sectores, subsectores y unidades institucionales que proveen bienes y servicios a la comunidad, redistribuyen el ingreso o la inversi\u00f3n p\u00fablica. Adem\u00e1s, busca identificar los sectores, subsectores e instituciones a las cuales se les asigna recursos p\u00fablicos a trav\u00e9s del presupuesto. <\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">(CONAC, Consejo Nacional de Armonizaci\u00f3n Contable, 2011)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para comprender este clasificador es necesario recordar que los componentes b\u00e1sicos de la econom\u00eda en un pa\u00eds, son seis: Sociedades No Financieras, Sociedades Financieras, Gobierno General, Hogares, Instituciones Sin Fines de Lucro que Sirven a los Hogares (ISFLSH), y Resto del Mundo. Que estos 6 sectores tambi\u00e9n son las principales cuentas que componen la clasificaci\u00f3n administrativa, y que permite que los registros sean homog\u00e9neos y arm\u00f3nicos entre s\u00ed. Evidentemente, existir\u00e1n subclasificaciones que hacen m\u00e1s precisas las cuentas que se manejan. <\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">(CONAC, Consejo Nacional de Armonizaci\u00f3n Contable, 2011)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n te presentamos un extracto de la codificaci\u00f3n de la clasificaci\u00f3n administrativa, para que recuerdes de manera general c\u00f3mo se estructura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estructura:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1 ESTRUCTURA Y CODIFICACI\u00d3N DE LA CLASIFICACI\u00d3N ADMINISTRATIVA.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>SECTOR P\u00daBLICO DE LA FEDERACI\u00d3N.<\/li><li>SECTOR P\u00daBLICO NO FINANCIERO.<\/li><li>GOBIERNO GENERAL CENTRAL.<\/li><li>Gobierno federal.<\/li><li>Poder Ejecutivo.<\/li><li>Poder Legislativo.<\/li><li>Poder Judicial.<\/li><li>\u00d3rganos aut\u00f3nomos.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">*Se incluir\u00e1 a nivel del quinto digito en forma consecutiva, los \u00f3rganos aut\u00f3nomos constitucionales existente y aquellos que posteriormente se constituyan.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Entidades Paraestatales y Fideicomisos No Empresariales y No Financieros<\/li><li>Instituciones P\u00fablicas de la seguridad social.<\/li><li>ENTIDADES PARAESTATALES EMPRESARIALES NO FINANCIERAS CON PARTICIPACI\u00d3N ESTATAL MAYORITARIA.<\/li><li>Entidades Paraestatales Empresariales No Financieras con Participaci\u00f3n estatal mayoritaria<\/li><li>Fideicomisos empresariales no financieros con Participaci\u00f3n Estatal Mayoritaria.<\/li><li>SECTOR PUBLICO FINANCIERO<\/li><li>BANCO DE MEXICO<\/li><li>ENTIDADES PARAESTATALES EMPRESARIALES FINANCIERAS MONETARIAS CON PARTICIPACI\u00d3N ESTATAL MAYORITARIA<\/li><\/ul>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">Fuente: Acuerdo por el que se emite la clasificaci\u00f3n administrativa, CONAC. 2011<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Clasificaci\u00f3n funcional del gasto<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">En esta tercera clasificaci\u00f3n los gastos son agrupados de acuerdo con el prop\u00f3sito y objetivo socioecon\u00f3mico que busca cada ente p\u00fablico. Es decir, se presentar\u00e1n los gastos de acuerdo con la naturaleza de los servicios que el Gobierno brinda a la poblaci\u00f3n, se identifican las siguientes funciones principales: funciones de Gobierno, De Desarrollo Social, de desarrollo econ\u00f3mico, y funciones no clasificadas. Gracias a este clasificador se pueden determinar los objetivos de las pol\u00edticas p\u00fablicas y de los recursos que se asignan a cada entidad. <\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">(CONAC, 2010)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este clasificador es de inter\u00e9s principalmente para la ciudadan\u00eda, ya que podr\u00e1 conocer a qu\u00e9 \u00e1reas va dirigido el presupuesto p\u00fablico que se recauda, tambi\u00e9n es \u00fatil para los altos funcionarios y para los analistas de pol\u00edticas p\u00fablicas.&nbsp; Con base en esta clasificaci\u00f3n se aplican an\u00e1lisis y estad\u00edsticas para estudiar las acciones del Gobierno y su eficiencia. Esta clasificaci\u00f3n ayuda a construir pol\u00edticas p\u00fablicas, as\u00ed como elaborar y evaluar los presupuestos de egresos ya que muestra las prioridades del gasto de cada Gobierno. <\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">(CONAC, 2010)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un punto importante a resaltar es que todos los clasificadores presupuestarios tienen una utilidad muy espec\u00edfica, pero utilizarlos en conjunto brinda mayor informaci\u00f3n con mejor objetividad, para comprender y analizar el gasto presupuestario. Es por ello que se requieren de varias clasificaciones para los prop\u00f3sitos anal\u00edticos.&nbsp; <\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">(CONAC, 2010)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otro punto a se\u00f1alar es que un ente p\u00fablico puede cumplir una o m\u00e1s funciones, as\u00ed como tambi\u00e9n una funci\u00f3n puede ser realizada por varias instituciones. Es decir, la clasificaci\u00f3n funcional del gasto no resulta excluyente. <\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">(CONAC, 2010)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En s\u00edntesis, el objetivo de esta clasificaci\u00f3n es informar \u201cla naturaleza de los servicios gubernamentales y la proporci\u00f3n del gasto p\u00fablico que se destina a cada servicio\u201d, en otras palabras este clasificador presupuestario permite conocer en qu\u00e9 se gasta y qu\u00e9 cantidad se destina a cada actividad. Como consecuencia, se podr\u00e1 desarrollar un an\u00e1lisis de las tendencias del gasto a lo largo del tiempo, lo cual puede ser empleado en Estudios Econ\u00f3micos y sociales e incluso desarrollar pol\u00edticas econ\u00f3micas.<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">(CONAC, 2010)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su estructura se compone de 3 principales d\u00edgitos. El nivel uno se conoce como \u201cfinalidad\u201d, el segundo nivel se denomina \u201cfunci\u00f3n\u201d, y el tercer nivel subfunci\u00f3n. La finalidad identifica si el gasto ejecutado pertenece a una actividad propia del Gobierno, si fue una erogaci\u00f3n por un servicio social que beneficie a la poblaci\u00f3n, si el gasto obedece a alguna actividad que fomente el desarrollo econ\u00f3mico, o bien, si el gasto corresponde a otra transacci\u00f3n no especificada.&nbsp; <\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">(CONAC, 2010)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe se\u00f1alar que tambi\u00e9n es posible agregar un cuarto d\u00edgito de acuerdo con las necesidades de cada orden de Gobierno, pero conservando la estructura b\u00e1sica de finalidad, funci\u00f3n y subfunci\u00f3n. A continuaci\u00f3n se presenta un extracto de la clasificaci\u00f3n funcional del gasto emitido por el CONAC, en el cual podr\u00e1s identificar claramente los 3 niveles principales que se han mencionado. <\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">(CONAC, 2010) <\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">2 Protecci\u00f3n ambiental<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Ordenaci\u00f3n de desechos<ol><li>Administraci\u00f3n del agua<\/li><li>Ordenaci\u00f3n de aguas residuales, drenaje y alcantarillado<\/li><li>Reducci\u00f3n de contaminaci\u00f3n<\/li><li>Protecci\u00f3n de la diversidad biol\u00f3gica y del paisaje<\/li><li>Otros de protecci\u00f3n ambiental<\/li><\/ol><\/li><\/ul>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">Fuente: Acuerdo por el que se emite la clasificaci\u00f3n funcional del gasto, CONAC. 2010<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Clasificaci\u00f3n Program\u00e1tica<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Este clasificador fue emitido en julio del 2013 y comenz\u00f3 a ser empleado en el Presupuesto de Egresos del a\u00f1o 2014. El objetivo de este clasificador, es catalogar los programas presupuestarios de las entidades de car\u00e1cter p\u00fablico para lograr ordenar las asignaciones de recursos p\u00fablicos. <\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">(CONAC, 2013)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La clasificaci\u00f3n program\u00e1tica distingue nueve programas principales con sus subprogramas correspondientes, los cuales son: subsidios, desempe\u00f1o de las funciones p\u00fablicas, programas administrativos y de apoyo, compromisos, obligaciones, programas de gasto federalizado, participaciones a entidades federativas y municipios, costo financiero, y adeudos de ejercicios fiscales anteriores. <\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">(CONAC, 2013)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al igual que en el resto de los clasificadores puedes consultarlos y obtener la definici\u00f3n detallada de cada uno de los rubros que se manejan, para comprender qu\u00e9 gastos se catalogar\u00eda dentro de cada cuenta.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Clasificador Econ\u00f3mico (Por Tipo de Gasto)<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Este clasificador fue emitido en el a\u00f1o 2010, y fue construido para relacionar las transacciones y operaciones efectuadas con recursos p\u00fablicos, con los grandes agregados econ\u00f3micos. Este clasificador identifica 5 rubros principales, los cuales son: gasto corriente, amortizaci\u00f3n de la deuda y disminuci\u00f3n de pasivos, pensiones y jubilaciones y participaciones.<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"> (CONAC, 2010)<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>El gasto corriente son aquellos egresos correspondientes a las transferencias que se realizan a las instituciones p\u00fablicas, para realizar gastos de consumos, arrendamientos y otros gastos de operaci\u00f3n.<\/li><li>Los gastos de capital son aquellos destinados a la inversi\u00f3n de capital y otras transferencias a entidades p\u00fablicas para financiar gastos de inversi\u00f3n.<\/li><li>La tercera categor\u00eda de amortizaci\u00f3n corresponde al pago de deuda adquirida y otros pasivos pactados con el sector p\u00fablico, privado o externo.<\/li><li>Las pensiones y jubilaciones son aquellos gastos que efect\u00faa el Gobierno federal, estatal, y municipal, o el Instituto de Seguridad Social correspondiente, para al pago de todas las personas pensionadas y jubiladas, o bien, a sus familiares<\/li><li>Finalmente, las participaciones son las erogaciones que cubren los ingresos para las entidades federativas, y municipios.<\/li><\/ul>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">(CONAC, 2010)<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Clasificador por Fuentes de Financiamiento<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Este clasificador fue publicado en el a\u00f1o 2013 y busca presentar los gastos p\u00fablicos de acuerdo con los recursos que se emplearon para su financiamiento, es decir, identifica la fuente o el origen de los ingresos que se han empleado para financiar el gasto. <\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">(CONAC, 2013)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta clasificaci\u00f3n reconoce dos categor\u00edas principales, pero cada unidad administrativa o instancia, podr\u00e1 agregar m\u00e1s niveles de acuerdo con las necesidades propias y respetando la estructura b\u00e1sica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El clasificador por fuente de financiamiento reconoce los recursos como etiquetados y no etiquetados. Los recursos no etiquetados son aquellos de libre disposici\u00f3n y pueden provenir de financiamientos. Dentro de esta categor\u00eda se encuentran los recursos fiscales (generados por la recaudaci\u00f3n de impuestos, contribuciones, etc.), financiamientos internos, financiamientos externos, ingresos propios, recursos federales, recursos estatales y otros recursos de libre disposici\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"> (CONAC, 2013)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En otras palabras, los recursos no etiquetados son aquellos que no presentan un fin espec\u00edfico, sino que se deber\u00e1n administrar para cumplir con las funciones p\u00fablicas con eficiencia y calidad, tales recursos pueden provenir de diferentes fuentes y se clasificar\u00e1n de acuerdo con aquella que les dio origen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, los recursos etiquetados son aquellos que ya tienen un destino espec\u00edfico y una indicaci\u00f3n de gastarse en cierta actividad. Existen tres grandes categor\u00edas dentro de este grupo: recursos federales, recursos estatales, u otros recursos de transferencias federales etiquetadas. <\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">(CONAC, 2013)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los recursos federales no etiquetados, son aquellos que la Federaci\u00f3n manda a los Estados y municipios para un fin espec\u00edfico, mientras que los recursos estatales no etiquetados son aquellos que los Estados destinan a los municipios en t\u00e9rminos de la Ley de Ingresos o presupuesto egresos estatales. La categor\u00eda de otros recursos de transferencias federales etiquetadas son aquellos que no provienen ni de la Federaci\u00f3n, ni del Estado.<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">(CONAC, 2013)<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Clasificador por Objeto del Gasto Armonizado<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Este clasificador permite catalogar las operaciones, de acuerdo con los criterios internacionales, y permite generar registros claros, precisos y \u00fatiles. El prop\u00f3sito fundamental de este clasificador es registrar los gastos de acuerdo con el proceso presupuestario. En otras palabras, el clasificador por objeto del gasto busca ordenar y presentar los gastos, que se hayan programado de manera previa en el presupuesto de egresos. <\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">(CONAC, 2009)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se clasificar\u00e1 a todas aquellas operaciones y transacciones que se efect\u00faan con el fin de obtener bienes o servicios, y los presenta de acuerdo con su naturaleza. En pocas palabras, el clasificador por objeto del gasto muestra en qu\u00e9 se gasta, y en qu\u00e9 cantidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este clasificador considera 3 niveles de desagregaci\u00f3n, siendo el primero el cap\u00edtulo, el segundo el concepto, y el tercero la partida. El cap\u00edtulo es el mayor nivel de clasificaci\u00f3n AR identificar los bienes y servicios que los entes p\u00fablicos requirieron. Dentro de este nivel se encuentran por ejemplo los servicios personales, materiales y suministros, servicios generales, transferencias, asignaciones, subsidios y otras ayudas, etc\u00e9tera. <\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">(CONAC, 2009)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El segundo nivel de este clasificador que se conoce como concepto, son los subconjuntos espec\u00edficos qu\u00e9 incluye cada cap\u00edtulo. As\u00ed pues, se identifican dentro del cap\u00edtulo de servicios personales los conceptos de: remuneraciones al personal de car\u00e1cter permanente, remuneraciones al personal de car\u00e1cter transitorio, remuneraciones adicionales y especiales, Seguridad Social, etc\u00e9tera.&nbsp; Como puedes observar en este segundo nivel se comienza a especificar el origen del gasto ejercido. <\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">(CONAC, 2009)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El tercer nivel de desagregaci\u00f3n, se conoce como partida, el cual describe concreta y detalladamente los bienes y servicios que se han adquirido. Este nivel se compone de partidas gen\u00e9ricas y espec\u00edficas. Las partidas gen\u00e9ricas corresponden al tercer d\u00edgito que se emplea en todos los niveles de Gobierno para lograr la armonizaci\u00f3n. Mientras que las partidas espec\u00edficas se identifican en el cuarto d\u00edgito, cuando los entes p\u00fablicos deciden emplear un nivel mayor de especificaci\u00f3n de acuerdo con sus necesidades pero respetando la estructura b\u00e1sica de cap\u00edtulo, concepto y partida gen\u00e9rica. <\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">(CONAC, 2009).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo te invitamos a revisar los siguientes enlaces ; Estados Presupuestarios, Financieros y Econ\u00f3micos,&nbsp; posteriormente cat\u00e1logo de bienes<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta aqu\u00ed, hemos concluido el an\u00e1lisis de los siete clasificadores presupuestarios reconocidos por el Consejo Nacional de Armonizaci\u00f3n Contable, CONAC. Como podr\u00e1s darte cuenta, el uso de los clasificadores no resulta excluyente entre s\u00ed sino complementario, ya que cada uno otorga un enfoque espec\u00edfico para analizar las transacciones que efect\u00faan las entidades de car\u00e1cter p\u00fablico. Gracias al uso de todos los clasificadores, se puede analizar la gesti\u00f3n de recursos p\u00fablicos y aplicar medidas preventivas y correctivas, o bien, desarrollar pol\u00edticas p\u00fablicas y programas que fortalezcan diversas \u00e1reas sociales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Deseamos que el presente recurso haya enriquecido tu conocimiento acerca del tema y facilitado tu proceso de aprendizaje. Gracias por acompa\u00f1arnos una vez m\u00e1s \u00a1Te esperamos para analizar juntos el pr\u00f3ximo tema!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Resumen e ideas relevantes<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Es importante que de lo anterior recuerdes que:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>El Clasificador por Rubro de Ingresos identifica el origen de los ingresos que perciben los entes p\u00fablicos en el uso de sus funciones<\/li><li>La clasificaci\u00f3n Administrativa permite identificar qui\u00e9n efect\u00faa el gasto<\/li><li>Clasificaci\u00f3n Funcional del Gasto cataloga los gastos p\u00fablicos de acuerdo con la funci\u00f3n o tipo de necesidad que satisface<\/li><li>La Clasificaci\u00f3n Program\u00e1tica clasifica los egresos seg\u00fan su programa y subprograma&nbsp;<\/li><li>El Clasificador Econ\u00f3mico distingue a los egresos seg\u00fan su tipo de Gasto<\/li><li>Clasificador por Fuentes de Financiamiento, reconoce y muestra si los egresos que se efect\u00faan tendr\u00e1n o no un fin espec\u00edfico<\/li><li>El Clasificador por Objeto del Gasto Armonizado clasifica los gastos de acuerdo con la naturaleza de los bienes, servicios, activos y pasivos financieros.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Fuentes de consulta<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>LGCG. (2018). LEY GENERAL DE CONTABILIDAD GUBERNAMENTAL. C\u00c1MARA DE DIPUTADOS DEL H. CONGRESO DE LA UNI\u00d3N, p\u00e1g. Art 41.<\/li><li>CONAC. (2009). ACUERDO POR EL QUE SE EMITE EL CLASIFICADOR POR OBJETO DEL GASTO. Obtenido de onsejo Nacional de Armonizaci\u00f3n Contable: <a href=\"https:\/\/www.conac.gob.mx\/work\/models\/CONAC\/normatividad\/NOR_01_02_006.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.conac.gob.mx\/work\/models\/CONAC\/normatividad\/NOR_01_02_006.pdf<\/a><\/li><li>CONAC. (2010). CLASIFICACI\u00d3N FUNCIONAL DEL GASTO (FINALIDAD, FUNCI\u00d3N Y SUBFUNCI\u00d3N). Obtenido de Consejo Nacional de Armonizaci\u00f3n Contable. Normatividad: <a href=\"https:\/\/www.conac.gob.mx\/work\/models\/CONAC\/normatividad\/NOR_01_02_003.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.conac.gob.mx\/work\/models\/CONAC\/normatividad\/NOR_01_02_003.pdf<\/a><\/li><li>CONAC. (2010). ACUERDO POR EL QUE SE EMITE EL CLASIFICADOR POR TIPO DE GASTO. Obtenido de Consejo Nacional de Armonizaci\u00f3n Contable: <a href=\"https:\/\/www.conac.gob.mx\/work\/models\/CONAC\/normatividad\/NOR_01_02_005.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.conac.gob.mx\/work\/models\/CONAC\/normatividad\/NOR_01_02_005.pdf<\/a><\/li><li>CONAC. (2013). CLASIFICADOR POR FUENTES DE FINANCIAMIENTO. Obtenido de Consejo Nacional de Armonizaci\u00f3n Contable: <a href=\"https:\/\/www.conac.gob.mx\/work\/models\/CONAC\/normatividad\/NOR_01_02_007.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.conac.gob.mx\/work\/models\/CONAC\/normatividad\/NOR_01_02_007.pdf<\/a><\/li><li>CONAC. (2013). ACUERDO por el que se emite la clasificaci\u00f3n program\u00e1tica (Tipolog\u00eda general). Obtenido de Consejo Nacional de Armonizaci\u00f3n Contable, normatividad: <a href=\"https:\/\/www.conac.gob.mx\/work\/models\/CONAC\/normatividad\/NOR_01_02_004.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.conac.gob.mx\/work\/models\/CONAC\/normatividad\/NOR_01_02_004.pdf<\/a><\/li><li>CONAC, C. N. (2009). CLASIFICADOR POR RUBROS DE INGRESOS. Obtenido de Clasificadores Presupuestarios: <a href=\"https:\/\/www.conac.gob.mx\/work\/models\/CONAC\/normatividad\/NOR_01_02_001.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.conac.gob.mx\/work\/models\/CONAC\/normatividad\/NOR_01_02_001.pdf<\/a><\/li><li>CONAC, Consejo Nacional de Armonizaci\u00f3n Contable. (07 de 07 de 2011). ACUERDO POR EL QUE SE EMITE LA CLASIFICACION ADMINISTRATIVA. Obtenido de Clasificadores Presupuestarios: <a href=\"https:\/\/www.conac.gob.mx\/work\/models\/CONAC\/normatividad\/NOR_01_02_002.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.conac.gob.mx\/work\/models\/CONAC\/normatividad\/NOR_01_02_002.pdf<\/a> <\/li><li>Davina Jacobs, J.-L. H. (2009). Clasificaci\u00f3n presupuestaria, Departamento de Finanzas P\u00fablicas. Obtenido de Fondo Monetario Internacional: <a href=\"https:\/\/blog-pfm.imf.org\/files\/fad-technical-manual-6-spanish-translation.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/blog-pfm.imf.org\/files\/fad-technical-manual-6-spanish-translation.pdf<\/a><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>1. Fundamentaci\u00f3n del tema Es de suma importancia que dentro de la formaci\u00f3n del Contador P\u00fablico se imparta el conocimiento de la t\u00e9cnica contable correspondiente al sector gubernamental. Especialmente, este tema tiene gran relevancia, toda vez que la Ley General de Contabilidad Gubernamental, se\u00f1ala en su art\u00edculo 41 que los entes p\u00fablicos deben disponer de &#8230; <a title=\"Clase digital 4. Clasificadores presupuestarios\" class=\"read-more\" href=\"https:\/\/blogs.ugto.mx\/contador\/clase-digital-4-clasificadores-presupuestarios\/\" aria-label=\"Leer m\u00e1s sobre Clase digital 4. Clasificadores presupuestarios\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":142,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[76],"tags":[117,77,118],"class_list":["post-3851","post","type-post","status-publish","format-standard","hentry","category-contabilidad-por-sectores","tag-alicia-sarahi-robles-martinez-2","tag-co310","tag-maria-guadalupe-garcia-cervantes-2"],"acf":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/blogs.ugto.mx\/contador\/wp-json\/wp\/v2\/posts\/3851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ugto.mx\/contador\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ugto.mx\/contador\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ugto.mx\/contador\/wp-json\/wp\/v2\/users\/142"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ugto.mx\/contador\/wp-json\/wp\/v2\/comments?post=3851"}],"version-history":[{"count":6,"href":"https:\/\/blogs.ugto.mx\/contador\/wp-json\/wp\/v2\/posts\/3851\/revisions"}],"predecessor-version":[{"id":4610,"href":"https:\/\/blogs.ugto.mx\/contador\/wp-json\/wp\/v2\/posts\/3851\/revisions\/4610"}],"wp:attachment":[{"href":"https:\/\/blogs.ugto.mx\/contador\/wp-json\/wp\/v2\/media?parent=3851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ugto.mx\/contador\/wp-json\/wp\/v2\/categories?post=3851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ugto.mx\/contador\/wp-json\/wp\/v2\/tags?post=3851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}